{"id":18438,"date":"2023-01-18T10:00:00","date_gmt":"2023-01-18T01:00:00","guid":{"rendered":"https:\/\/www.s-lecfilm.com\/en-innovation\/"},"modified":"2024-06-21T16:34:14","modified_gmt":"2024-06-21T07:34:14","slug":"en-innovation","status":"publish","type":"page","link":"https:\/\/www.s-lecfilm.com\/de\/innovation\/","title":{"rendered":"\/de\/innovation\/"},"content":{"rendered":"<div class=\"frame pt-0\" style=\"clear: both;\">\n\t<div class=\"hero-flame\" style=\"height:62vh;margin:0;\">\n\t\t<div class=\"hero-flame-bg\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"hero-flame-bg-img\" src=\"https:\/\/www.s-lecfilm.com\/wp-content\/uploads\/hero-innovation-1.webp\" width=\"1920\" height=\"1054\" alt=\"Men and women striving to innovate the functionality and design of PVB interlayer for glass.\" style=\"object-position:50% 50%;\">\n\t\t<\/div>\n\t\t<div class=\"hero-flame-content\">\n\t\t\t\t\t\t\t<div class=\"hero-text\">\n\t\t\t\t\t<div class=\"hero-text-title\">\n\t\t\t\t\t\tInnovation\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"hero-text-subtitle\">\n\t\t\t\t\t\t\tDie Entwicklung der Zukunft der Verglasung\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\n<div class=\"frame pt-0 pb-0\">\n\t\n<div class=\"container\">\n\t\n<H2 class=\"c-title-level02 section-subtitle\">Was ist eine PVB-Zwischenschicht f\u00fcr Verbundglas?<\/H2>\n\n<div class=\"c-layout-frame section-flame\">\n\t\t<div class=\"row align-items-center\">\n\t\t<div class=\"col-lg-6\">\n\t\t\t<div class=\"feature-img text-center\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.s-lecfilm.com\/wp-content\/uploads\/f9adc73ffb4911a9cba7dbd0b3fc14c5-2-1024x620.webp\"  alt=\"S-LEC\u2122PVB interlayer film for laminated glass provides a variety of functions and values.\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"col-lg-6\">\n\t\t\t<div class=\"feature-cont\">\n\t\t\t\t<div class=\"acf-innerblocks-container\">\n\n<p>Laminiertes Glass ist eine Art von Sicherheitsglas, das durch Laminieren einer Zwischenschicht zwischen zwei Glasscheiben bei hoher Temperatur und hohem Druck in einem Autoklaven hergestellt wird. PVB-Zwischenschichten werden haupts\u00e4chlich f\u00fcr laminiertes Glass verwendet, da sie den einzigartigen Vorteil haben, dass sie am Glas haften, durchdringen und sto\u00dffest sind.<\/p>\n\n\n\n<p>Unsere PVB-Zwischenschichtfolie f\u00fcr Laminiertes Glass, S-LEC\u2122 Film, wird weltweit eingesetzt und bietet Vorteile wie:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Hohe Transparenz &#8211; F\u00fcr die Klarheit der Verglasung.<\/li>\n\n\n\n<li>Sicherheit &#8211; Splitterfrei, absorbiert St\u00f6\u00dfe und verhindert Unf\u00e4lle.<\/li>\n\n\n\n<li>Schutz &#8211; Widersteht Schl\u00e4gen mit einem Hammer oder Glasschneider.<\/li>\n\n\n\n<li>UV-Schutz &#8211; blockt 99 % der ultravioletten Strahlen ab.<\/li>\n\n\n\n<li>Design -Gradient oder Farbe mit verschiedenen Folienst\u00e4rken.<\/li>\n\n\n\n<li>Solar Kontrolle &#8211; W\u00e4rmereduzierung in Autos oder Geb\u00e4uden.<\/li>\n\n\n\n<li>Akustik &#8211; Ger\u00e4uschlosigkeit durch Abschirmung von Au\u00dfenger\u00e4uschen.<\/li>\n\n\n\n<li>Head-up Display &#8211; Anpassungsf\u00e4higkeit mit HUD f\u00fcr ein klares Bild.<\/li>\n<\/ul>\n\n<\/div>\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n\n<H2 class=\"c-title-level02 section-subtitle\">S-LEC\u2122 Film Entwicklungsgeschichte<\/H2>\n\n<div class=\"container\">\r\n\t<div class=\"container\">\r\n\t\t<div class=\"section-flame\">\r\n\t\t\t<div class=\"row justify-content-end align-items-center\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"col-lg-6 order-lg-0 order-1\">\r\n\t\t\t\t\t\t<div class=\"feature-cont\">\n\t<div class=\"feature-cont-title\"><\/div>\n\t<div class=\"feature-cont-text\">\n\t\tMit \u00fcber 60 Jahren Erfahrung in der Herstellung und Entwicklung von PVB-Zwischenschichten. Die erste S-LEC\u2122 Folie, die 1958 eingef\u00fchrt wurde, um das Zersplittern von Glas bei einem Aufprall zu verhindern, markierte den Beginn unserer f\u00fchrenden Rolle in der PVB-Zwischenschichtfolie f\u00fcr Laminiertes Glass. Als Antwort auf den Bedarf an verschiedenen Funktionen und Designmerkmalen f\u00fcr Automobil- und Architekturglas haben wir unsere PVB-Zwischenschicht-L\u00f6sungen erweitert, um die Unannehmlichkeiten zu reduzieren, z. B. durch L\u00e4rm- und W\u00e4rmereduzierung. Dar\u00fcber hinaus haben wir die M\u00f6glichkeit, unsere Funktionen mit Farbverl\u00e4ufen und schattierten hellen und dunklen Farben zu kombinieren, um sowohl \u00e4sthetisch ansprechendes als auch funktionales Glas zu erhalten. In einer Folie k\u00f6nnen wir Technologien wie die keilf\u00f6rmige Zwischenschicht f\u00fcr Head-up-Displays kombinieren, um klare Bilder mit zus\u00e4tzlichen Schall- und W\u00e4rmed\u00e4mmeffekten anzuzeigen.<br \/>\n<br \/>\nBei SEKISUI S-LEC haben wir uns verpflichtet, neue wertvolle L\u00f6sungen durch PVB-Zwischenschichtfolien f\u00fcr Laminiertes Glass zu schaffen, um zu den Entwicklungen in der st\u00e4ndig wachsenden Automobil- und Architekturindustrie beizutragen.\t<\/div>\n<\/div>\n<div class=\"row d-brochure-bg-btn-wrap justify-content-end with-accent align-items-center mt-4 mx-0\">\n\t\t<div class=\"col-lg-5 d-brochure-bg-btn is-inner-btn with-accent\">\n\t\t\t<\/div>\n<\/div>\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<div class=\"col-lg-6 order-lg-1\">\r\n\t\t\t\t\t\t<div class=\"youtube_wrap\">\n\t<div class=\"youtube_area un_youtube_area\">\n\t\t<script src=\"https:\/\/www.youtube.com\/iframe_api\"><\/script>\n\t\t<iframe loading=\"lazy\" data-cookieconsent=\"necessary\" width=\"560\" height=\"315\" src=\"\/\/www.youtube.com\/embed\/6dXg21WVifg?enablejsapi=1&amp;origin=https%3A%2F%2Fwww.s-lecfilm.com\" title=\"\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen=\"\" data-gtm-yt-inspected-7440638_38=\"true\" id=\"900282223\"><\/iframe>\n\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/div>\r\n<\/div>\r\n\n\n<H2 class=\"c-title-level02 section-subtitle\">Fortschrittliche Glasl\u00f6sungen<\/H2>\n\n<div class=\"c-layout-frame section-flame\">\n\t\t<div class=\"row align-items-center\">\n\t\t<div class=\"col-lg-6\">\n\t\t\t<div class=\"feature-img text-center\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.s-lecfilm.com\/wp-content\/uploads\/shutterstock_670152970-1024x683-1-1024x683.webp\"  alt=\"Glass with S-LEC\u2122 film that brings advanced solutions\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"col-lg-6\">\n\t\t\t<div class=\"feature-cont\">\n\t\t\t\t<div class=\"acf-innerblocks-container\">\n\n<p>Die Trends in der zeitgen\u00f6ssischen Architektur haben dazu gef\u00fchrt, dass immer aufwendigere und gr\u00f6\u00dfere Glasfl\u00e4chen angestrebt werden, um R\u00e4ume heller und optisch attraktiver zu gestalten. Diese Trends haben zu einem Bedarf an funktionalem Glas gef\u00fchrt, das Sicherheit, Schutz und Komfort bietet. Mit der Vergr\u00f6\u00dferung der Glasfl\u00e4chen sind die Menschen immer h\u00e4ufiger der Infrarotstrahlung und der steigenden Temperatur ausgesetzt, und mit der Diversifizierung der Wohnformen und dem zunehmenden Interesse am Schutz der Privatsph\u00e4re wird dem Schallschutz in Geb\u00e4uden gro\u00dfe Aufmerksamkeit geschenkt.<\/p>\n\n\n\n<p>S-LEC\u2122 Solar Control Film wurde entwickelt, um die Infrarotstrahlung zu reduzieren und so zus\u00e4tzliche Stromeinsparungen zu erzielen, indem der Einsatz von Klimaanlagen verringert wird. S-LEC\u2122 Sound Acoustic Film tr\u00e4gt zur Verbesserung der Schalld\u00e4mmung bei, um komfortable R\u00e4ume zu schaffen.<\/p>\n\n\n<div class=\"c-button-type01 row justify-content-center\">\n\t<div class=\"col-lg-5 d-brochure-bg-btn is-inner-btn btn-size-medium\">\n\t\t<a href=\"\/de\/download\/ArchG\/\" target=\"_blank\">\n\t\t\t<button type=\"button\" class=\"btn btn-primary\">Brosch\u00fcren herunterladen<\/button>\n\t\t<\/a>\n\t<\/div>\n<\/div>\n\n<\/div>\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n\n<H1 class=\"c-title-level02 section-subtitle\">Glas-Innovationen<\/H1>\n\n<div class=\"c-layout-frame section-flame\">\n\t\t<div class=\"row align-items-center\">\n\t\t<div class=\"col-lg-6 order-lg-1 order-0\">\n\t\t\t<div class=\"feature-img text-center\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.s-lecfilm.com\/wp-content\/uploads\/shutterstock_2032543370-1024x683.webp\"  alt=\"S-LEC\u2122 Film that brings advanced solutions for EV glass\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"col-lg-6 order-lg-0 order-1\">\n\t\t\t<div class=\"feature-cont\">\n\t\t\t\t<div class=\"acf-innerblocks-container\">\n\n<p>S-LEC\u2122 Film bietet eine Reihe von L\u00f6sungen als PVB-Zwischenschicht f\u00fcr Laminiertes Glass in der Automobilindustrie.<\/p>\n\n\n\n<p>Zus\u00e4tzlich zu den Sicherheitsmerkmalen blockiert unsere Folie auch mehr als 99 % der UV-Strahlen, die in den Fahrzeuginnenraum eindringen, und sch\u00fctzt so die Haut und wertvolle Gegenst\u00e4nde vor Sonnensch\u00e4den. Mit einer breiten Palette von Farbverlaufs- oder Farbfolien k\u00f6nnen wir gestaltbare Verglasungen herstellen.<\/p>\n\n\n\n<p>Im Rahmen unserer Vision entwickeln wir vor allem L\u00f6sungen, die zu einer nachhaltigeren, innovativen Gesellschaft beitragen k\u00f6nnen. S-LEC\u2122 Solar Control Film wurde beispielsweise entwickelt, um die Konnektivit\u00e4t von Ger\u00e4ten und Sensoren im Auto nicht zu beeintr\u00e4chtigen und Energie bei der Verwendung von Klimaanlagen zu sparen, um die Reichweite von Elektrofahrzeugen zu erh\u00f6hen.<\/p>\n\n\n\n<p>SEKISUI S-LEC stellt sich der Herausforderung neuer Innovationen zur L\u00f6sung sozialer Probleme, indem es eine Vielzahl von L\u00f6sungen in eine PVB-Zwischenschicht integriert.<\/p>\n\n\n<div class=\"c-button-type01 row justify-content-center\">\n\t<div class=\"col-lg-5 d-brochure-bg-btn is-inner-btn btn-size-medium\">\n\t\t<a href=\"\/de\/download\/AutoG\/\" target=\"_blank\">\n\t\t\t<button type=\"button\" class=\"btn btn-primary\">Brosch\u00fcren herunterladen<\/button>\n\t\t<\/a>\n\t<\/div>\n<\/div>\n\n<\/div>\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n\n<H2 class=\"c-title-level02 section-subtitle\">Offene Innovation<\/H2>\n\n<div class=\"c-layout-frame section-flame\">\n\t\t<div class=\"row align-items-center\">\n\t\t<div class=\"col-lg-6\">\n\t\t\t<div class=\"feature-img text-center\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.s-lecfilm.com\/wp-content\/uploads\/innovation-2-1024x683.webp\"  alt=\"People who provide value with open innovation that actively incorporate technology in different industries\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"col-lg-6\">\n\t\t\t<div class=\"feature-cont\">\n\t\t\t\t<div class=\"acf-innerblocks-container\">\n\n<p>Es gibt viele Ver\u00e4nderungen in der heutigen Gesellschaft, die sich auf die Entwicklungen und Trends f\u00fcr die Zukunft der Architektur- und Automobilindustrie auswirken. Unsere Kollegen rund um den Globus nutzen unsere Markt- und Trendforschung und unser technisches Know-how, um fortschrittliche Verglasungsl\u00f6sungen f\u00fcr die Zukunft zu entwickeln.<\/p>\n\n\n\n<p>  Um die neuesten Innovationen bei S-LEC\u2122 PVB interlayer film f\u00fcr Laminiertes Glass zu integrieren, arbeiten wir mit unseren Partnern weltweit zusammen. Durch offene Innovation sind wir bestrebt, proaktiv Technologien aus verschiedenen Branchen einzubeziehen, um die M\u00f6glichkeiten von PVB-L\u00f6sungen f\u00fcr laminiertes Glass zu verbessern.<\/p>\n\n<\/div>\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n\n<H2 class=\"c-title-level02 section-subtitle\">Globale Forschung<\/H2>\n\n<div class=\"c-layout-frame section-flame\">\n\t\t<div class=\"row align-items-center\">\n\t\t<div class=\"col-lg-6 order-lg-1 order-0\">\n\t\t\t<div class=\"feature-img text-center\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.s-lecfilm.com\/wp-content\/uploads\/innovation-3-1024x585.webp\"  alt=\"Research centers of SEKISUI S-LEC in the world\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"col-lg-6 order-lg-0 order-1\">\n\t\t\t<div class=\"feature-cont\">\n\t\t\t\t<div class=\"acf-innerblocks-container\">\n\n<p>F\u00fcr k\u00fcnftige S-LEC\u2122 Film-Entwicklungen haben wir vier globale Forschungszentren in unseren Hauptgesch\u00e4ftsregionen (Japan, China, Europa und den Vereinigten Staaten) eingerichtet. Jedes einzelne Forschungszentrum geht unterschiedliche Entwicklungen auf der Grundlage von Trends und Bed\u00fcrfnissen in der jeweiligen Region an und erm\u00f6glicht so die Entwicklung von Technologien f\u00fcr die richtigen regionalen M\u00e4rkte und Zielanwendungen und st\u00e4rkt die Planung und Entwicklung neuer PVB-Zwischenschichten mit unseren Partnern.<\/p>\n\n\n\n<p>Bei SEKISUI S-LEC ist unser globales Team unserer Vision verpflichtet, das NEUE zu machen. Bitte kontaktieren Sie uns, wenn Sie mit unseren globalen Forschungsteams zusammenarbeiten m\u00f6chten.<\/p>\n\n<\/div>\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n\n<H2 class=\"c-title-level02 section-subtitle\">Eine Herausforderung f\u00fcr die Zukunft<\/H2>\n\n<div class=\"c-layout-frame section-flame\">\n\t\t<div class=\"row align-items-center\">\n\t\t<div class=\"col-lg-6\">\n\t\t\t<div class=\"feature-img text-center\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.s-lecfilm.com\/wp-content\/uploads\/AdobeStock_358683651-1-1024x587.webp\"  alt=\"Innovation for the Earth to create peace of mind leading to the future\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"col-lg-6\">\n\t\t\t<div class=\"feature-cont\">\n\t\t\t\t<div class=\"acf-innerblocks-container\">\n\n<p>Die SEKISUI CHEMICAL Group hat ihre Vision f\u00fcr das Jahr 2030 als &#8222;Innovation f\u00fcr die Erde&#8220; formuliert, die den starken Wunsch verk\u00f6rpert, die Lebensinfrastruktur zu unterst\u00fctzen und einen &#8222;Seelenfrieden zu schaffen, der bis in die Zukunft reicht&#8220;.<\/p>\n\n\n\n<p>Unser Ziel ist es, durch unser Unternehmen und unsere Produkte soziale Probleme zu l\u00f6sen, um die Nachhaltigkeit der Erde und der Gesellschaft w\u00e4hrend des gesamten Produktlebenszyklus von der Entwicklung bis zur Auslieferung zu verbessern und PVB-Zwischenschichten zu entwickeln, die einen positiven Beitrag zur globalen Umwelt leisten.<\/p>\n\n\n\n<p>Wir werden weiterhin Glashersteller, Automobilhersteller und andere Unternehmen weltweit bei der Bereitstellung und Entwicklung innovativer S-LEC\u2122 Film-L\u00f6sungen f\u00fcr Glas unterst\u00fctzen.<\/p>\n\n<\/div>\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n\n<H2 class=\"c-title-level02 section-subtitle\">Unsere Dienstleistungen f\u00fcr Ihre Innovation<\/H2>\n\n<div class=\"c-layout-frame section-flame\">\n\t\t<div class=\"row align-items-center\">\n\t\t<div class=\"col-lg-6 order-lg-1 order-0\">\n\t\t\t<div class=\"feature-img text-center\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.s-lecfilm.com\/wp-content\/uploads\/shutterstock_2076774124-1024x576-1-1-1-1024x576.webp\"  alt=\"Glass development support from project design and proposes optimal solutions\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"col-lg-6 order-lg-0 order-1\">\n\t\t\t<div class=\"feature-cont\">\n\t\t\t\t<div class=\"acf-innerblocks-container\">\n\n<p>Wir bieten Ihnen unsere flexiblen Dienstleistungen zur Anpassung an. Beziehen Sie unser Beratungsteam in die Designphase Ihres Projekts ein. Auf diese Weise k\u00f6nnen wir Sie bei der Entwicklung einer ma\u00dfgeschneiderten L\u00f6sung unterst\u00fctzen, die Ihren Anforderungen entspricht.<\/p>\n\n\n\n<p>Da wir weltweit t\u00e4tig sind, gibt es immer eine M\u00f6glichkeit, mit Ihnen zusammenzuarbeiten. Au\u00dferdem investieren wir gerne in Produktinnovationen. Wir laden Sie ein, mit uns in Kontakt zu treten, wenn Sie spezielle Anforderungen f\u00fcr Ihr Projekt haben. Lassen Sie uns wissen, wie wir den Anforderungen der zuk\u00fcnftigen Entwicklungen gerecht werden k\u00f6nnen.<\/p>\n\n\n\n<p>Wenn Sie mehr \u00fcber die S-LEC\u2122 PVB interlayer film f\u00fcr Laminiertes Glass erfahren m\u00f6chten, laden Sie bitte unsere ausf\u00fchrlichen Brosch\u00fcren herunter oder nehmen Sie Kontakt mit uns auf.<\/p>\n\n\n<div class=\"c-button-type01 row justify-content-center\">\n\t<div class=\"col-lg-5 d-brochure-bg-btn is-inner-btn btn-size-medium\">\n\t\t<a href=\"\/de\/download\/all\/\" target=\"_blank\">\n\t\t\t<button type=\"button\" class=\"btn btn-primary\">Brosch\u00fcren herunterladen<\/button>\n\t\t<\/a>\n\t<\/div>\n<\/div>\n\n<\/div>\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n\n<H2 class=\"c-title-level02 section-subtitle\">L\u00f6sung<\/H2>\n\n\n<p>SEKISUI S-LEC bietet eine Vielzahl von L\u00f6sungen f\u00fcr den Automobil- und Architekturmarkt.<\/p>\n\n\n<div class=\"subtab-flame\">\r\n  <ul class=\"subtab\">\r\n\t\t\t\t\t\t\t\t\t<li class=\"select\"><span>Design<\/span><\/li>\r\n\t\t\t\t\t\t\t<li class=\"\"><span>Solarsteuerung<\/span><\/li>\r\n\t\t\t\t\t\t\t<li class=\"\"><span>Akustik<\/span><\/li>\r\n\t\t\t\t\t\t\t<li class=\"\"><span>Premium UV-Schutz<\/span><\/li>\r\n\t\t\t\t\t\t<\/ul>\r\n<\/div>\r\n\r\n\n\n<div class=\"c-subtab-content\">\n\t<div class=\"subicon\">\n\t\t\t\t\t\t\n<div class=\"c-subtab-frame frame py-0\">\n\t\t<div class=\"container\">\n\t\t\t\t\n<div class=\"c-layout-frame section-flame\">\n\t\t<div class=\"row align-items-center\">\n\t\t<div class=\"col-lg-6 order-lg-1 order-0\">\n\t\t\t<div class=\"feature-img text-center\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.s-lecfilm.com\/wp-content\/uploads\/top_designauto_hero-3-1-1-1024x579.webp\"  alt=\"S-LEC\u2122 Design film applied on a blue car that talks about the design of the PVB interlayer for glass.\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"col-lg-6 order-lg-0 order-1\">\n\t\t\t<div class=\"feature-cont\">\n\t\t\t\t<div class=\"acf-innerblocks-container\">\n<Div class=\"c-title-level03 feature-cont-title\">\n\t\t<img decoding=\"async\" src=\"https:\/\/www.s-lecfilm.com\/wp-content\/uploads\/slec_icon_15.svg\" alt=\"Laminated Glass Design\">\n\t\tDesign<\/Div>\n\n\n\n<p>S-LEC\u2122-Folien sind derzeit in einer breiten Palette von Standardfarben und kundenspezifischen Farboptionen mit verschiedenen Tvis-Werten (Visible Light Transmittance) erh\u00e4ltlich, um verschiedene Glaskombinationen entsprechend dem Fahrzeugkonzept zu optimieren.<\/p>\n\n\n\n<p>Dar\u00fcber hinaus umfasst unser Angebot auch breite Farbverl\u00e4ufe, die von 2% bis zu &gt;70% Tvis (Visible Light Transmittance) reichen. Durch die Anpassung an eine Windschutz- oder Heckscheibe schafft es ein Gef\u00fchl von Offenheit und Sch\u00f6nheit durch sanfte Abstufungen und bietet ein fortschrittliches Design f\u00fcr Automobilglas.<\/p>\n\n\n<div class=\"c-button-type02 feature-cont-btn text-right\">\n\t<a href=\"\/de\/design-auto\/\" >\n\t\t<button class=\"btn btn-primary is-caret-link\">\n\t\t\t\t\t\t\tMehr erfahren\t\t\t\t\t\t<\/button>\n\t<\/a>\n<\/div>\n\n<\/div>\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n\t<\/div>\n\t<\/div>\n\n\n<div class=\"c-subtab-frame frame py-0\">\n\t\t<div class=\"container\">\n\t\t\t\t\n<div class=\"c-layout-frame section-flame\">\n\t\t<div class=\"row align-items-center\">\n\t\t<div class=\"col-lg-6 order-lg-1 order-0\">\n\t\t\t<div class=\"feature-img text-center\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.s-lecfilm.com\/wp-content\/uploads\/aboutus_contents_hero-2-1024x650-1-1024x650.webp\"  alt=\"A woman near the glass that transmits the visible light and blocks near-infrared rays and UV lights\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"col-lg-6 order-lg-0 order-1\">\n\t\t\t<div class=\"feature-cont\">\n\t\t\t\t<div class=\"acf-innerblocks-container\">\n<Div class=\"c-title-level03 feature-cont-title\">\n\t\t<img decoding=\"async\" src=\"https:\/\/www.s-lecfilm.com\/wp-content\/uploads\/slec_icon_14.svg\" alt=\"Solar Control Performance for laminated glass\">\n\t\tSolar<\/Div>\n\n\n\n<p>Laminiertes Glass mit S-LEC\u2122 Solar Control Film blockiert Infrarot- und UV-Strahlen (Ultraviolett), l\u00e4sst aber sichtbare Lichtstrahlen f\u00fcr optische Klarheit zu, ohne die elektromagnetischen \u00dcbertragungen zu blockieren, die f\u00fcr die Kommunikation von Mobiltelefonen und Sensoren notwendig sind. Das sonnenabsorbierende Glas von S-LEC\u2122 Solar Control Film sch\u00fctzt die Menschen, weil der Innenraum k\u00fchler bleibt, so dass die Haut nicht verbrennt.<\/p>\n\n\n\n<p>Erleben Sie eine komfortable, effiziente, vernetzte und sichere Umgebung.<\/p>\n\n\n<div class=\"c-button-type02 feature-cont-btn text-right\">\n\t<a href=\"\/de\/solar-auto\/\" >\n\t\t<button class=\"btn btn-primary is-caret-link\">\n\t\t\t\t\t\t\tMehr erfahren\t\t\t\t\t\t<\/button>\n\t<\/a>\n<\/div>\n\n<\/div>\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n\t<\/div>\n\t<\/div>\n\n\n<div class=\"c-subtab-frame frame py-0\">\n\t\t<div class=\"container\">\n\t\t\t\t\n<div class=\"c-layout-frame section-flame\">\n\t\t<div class=\"row align-items-center\">\n\t\t<div class=\"col-lg-6 order-lg-1 order-0\">\n\t\t\t<div class=\"feature-img text-center\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.s-lecfilm.com\/wp-content\/uploads\/solar-auto-9-1024x620-1.webp\"  alt=\"A child sleeps deeply in a car, thanks to sound insulation glass reducing outside noise and enhancing comfort.\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"col-lg-6 order-lg-0 order-1\">\n\t\t\t<div class=\"feature-cont\">\n\t\t\t\t<div class=\"acf-innerblocks-container\">\n<Div class=\"c-title-level03 feature-cont-title\">\n\t\t<img decoding=\"async\" src=\"https:\/\/www.s-lecfilm.com\/wp-content\/uploads\/slec_icon_13.svg\" alt=\"Sound Acoustic for laminated glass\">\n\t\tTon<\/Div>\n\n\n\n<p>S-LEC\u2122 Sound Acoustic Film kann verwendet werden, um Au\u00dfenger\u00e4usche wie Verkehr, Wind und andere st\u00f6rende Ger\u00e4usche abzuschirmen, um Ablenkungen f\u00fcr Menschen auszuschalten und ein friedliches, ruhiges Erlebnis zu schaffen.  <\/p>\n\n\n\n<p>Sie k\u00f6nnen akustische Qualit\u00e4t mit anderen Funktionen oder Designs kombinieren, z. B. mit Sonnenschutz oder Sichtschutzfarben, indem Sie Schallschutzfolien und andere Technologien in das laminierte Glass einarbeiten.<\/p>\n\n\n<div class=\"c-button-type02 feature-cont-btn text-right\">\n\t<a href=\"\/de\/sound-auto\/\" >\n\t\t<button class=\"btn btn-primary is-caret-link\">\n\t\t\t\t\t\t\tMehr erfahren\t\t\t\t\t\t<\/button>\n\t<\/a>\n<\/div>\n\n<\/div>\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n\t<\/div>\n\t<\/div>\n\n\n<div class=\"c-subtab-frame frame py-0\">\n\t\t<div class=\"container\">\n\t\t\t\t\n<div class=\"c-layout-frame section-flame\">\n\t\t<div class=\"row align-items-center\">\n\t\t<div class=\"col-lg-6 order-lg-1 order-0\">\n\t\t\t<div class=\"feature-img text-center\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.s-lecfilm.com\/wp-content\/uploads\/puvchealth_hero-2-1024x683.webp\"  alt=\"A woman who thinks a solution that protects people from ultraviolet rays by PVB interlayer\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"col-lg-6 order-lg-0 order-1\">\n\t\t\t<div class=\"feature-cont\">\n\t\t\t\t<div class=\"acf-innerblocks-container\">\n<Div class=\"c-title-level03 feature-cont-title\">\n\t\t<img decoding=\"async\" src=\"https:\/\/www.s-lecfilm.com\/wp-content\/uploads\/slec_icon_01-1.svg\" alt=\"Protecting people and things by UV blocking\">\n\t\tPremium UV-Schutz<\/Div>\n\n\n\n<p>Die Nachfrage nach Glas, das vor UV-Strahlung sch\u00fctzen kann, steigt aufgrund der vielen gesundheitlichen und kosmetischen Bedenken, die mit Sonneneinstrahlung verbunden sind. Diese Bedenken reichen von jungen Erwachsenen, die sich Sorgen \u00fcber eine vorzeitige Alterung aufgrund von Sonneneinstrahlung machen, bis hin zu Eltern, die kleine Kinder mit empfindlicher Haut und einem h\u00f6heren Sonnenbrandrisiko sch\u00fctzen m\u00f6chten.<\/p>\n\n\n\n<p>Laminiertes Glass mit S-LEC\u2122 Premium UV-Schutz Film sch\u00fctzt die Haut f\u00fcr diejenigen, die UV-Schutz ben\u00f6tigen, um Gesundheitsrisiken zu reduzieren.<\/p>\n\n\n<div class=\"c-button-type02 feature-cont-btn text-right\">\n\t<a href=\"\/de\/puv-auto\/\" >\n\t\t<button class=\"btn btn-primary is-caret-link\">\n\t\t\t\t\t\t\tMehr erfahren\t\t\t\t\t\t<\/button>\n\t<\/a>\n<\/div>\n\n<\/div>\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\n\t<\/div>\n\t<\/div>\n\n\t<\/div>\n<\/div>\n\n<\/div>\n\n<\/div>\n\n\n\n<div class=\"frame is-bg-img c-more-detail \">\n\t<div class=\"container\">\n\t\t<div class=\"row justify-content-center\">\n\t\t\t<div class=\"col-lg-10\">\n\t\t\t\t<div class=\"row\">\n\t\t\t\t\t<div class=\"col-lg-7 mb-5 mb-lg-0\">\n\t\t\t\t\t\t<div class=\"contact-footer-text\">\n\t\t\t\t\t\t\tM\u00f6chten Sie mehr erfahren?\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"contact-footer-btn\">\n\t\t\t\t\t\t\t<a href=\"\/de\/download\/all\/\" target=\"_blank\">\n\t\t\t\t\t\t\t\t<button class=\"btn btn-primary fa-download-check\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tDownloads\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a href=\"\/de\/download\/Inquiry\/\" target=\"_blank\">\n\t\t\t\t\t\t\t\t<button class=\"btn btn-primary is-external-link\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tKontakt\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"col-lg-5\">\n\t\t\t\t\t\t<div class=\"contact-footer-img\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.s-lecfilm.com\/wp-content\/uploads\/thankyou_hero-1-1-1024x576.webp\" alt=\"Those who want to know more about S-LEC\u2122 Film\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":7,"featured_media":0,"parent":0,"menu_order":213,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_oasis_is_in_workflow":0,"_oasis_original":0,"om_disable_all_campaigns":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"page_category":[106,132,120],"class_list":["post-18438","page","type-page","status-publish","hentry"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.6.2 - aioseo.com -->\n\t\t<meta name=\"description\" content=\"Um die neuesten Innovationen bei PVB-Zwischenschichtfolien f\u00fcr Laminiertes Glass zu integrieren, stellen wir uns gemeinsam mit unseren Partnern weltweit der Herausforderung der offenen Innovation.\" \/>\n\t\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t\t<meta name=\"google-site-verification\" content=\"LGoHK3imcI57fEDyHDnPGNxrBKyRAWvyS1_pmekTNEU\" \/>\n\t\t<link rel=\"canonical\" href=\"https:\/\/www.s-lecfilm.com\/de\/innovation\/\" \/>\n\t\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.6.2\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"SEKISUI S-LEC\" \/>\n\t\t<meta property=\"og:type\" content=\"website\" \/>\n\t\t<meta property=\"og:title\" content=\"PVB-Zwischenschicht Innovation | SEKISUI S-LEC\" \/>\n\t\t<meta property=\"og:description\" content=\"Um die neuesten Innovationen bei PVB-Zwischenschichtfolien f\u00fcr Laminiertes Glass zu integrieren, stellen wir uns gemeinsam mit unseren Partnern weltweit der Herausforderung der offenen Innovation.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.s-lecfilm.com\/de\/innovation\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.s-lecfilm.com\/wp-content\/uploads\/2023\/01\/hero-innovation.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.s-lecfilm.com\/wp-content\/uploads\/2023\/01\/hero-innovation.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t\t<meta property=\"og:image:height\" content=\"659\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"PVB-Zwischenschicht Innovation | SEKISUI S-LEC\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Um die neuesten Innovationen bei PVB-Zwischenschichtfolien f\u00fcr Laminiertes Glass zu integrieren, stellen wir uns gemeinsam mit unseren Partnern weltweit der Herausforderung der offenen Innovation.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.s-lecfilm.com\/wp-content\/uploads\/2023\/01\/hero-innovation.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.s-lecfilm.com\\\/de\\\/innovation\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.s-lecfilm.com\\\/de\\\/#listItem\",\"position\":1,\"name\":\"Zu Hause\",\"item\":\"https:\\\/\\\/www.s-lecfilm.com\\\/de\\\/\",\"nextItem\":\"https:\\\/\\\/www.s-lecfilm.com\\\/de\\\/innovation\\\/#listItem\"},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.s-lecfilm.com\\\/de\\\/innovation\\\/#listItem\",\"position\":2,\"name\":\"\\\/de\\\/innovation\\\/\",\"previousItem\":\"https:\\\/\\\/www.s-lecfilm.com\\\/de\\\/#listItem\"}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.s-lecfilm.com\\\/de\\\/#organization\",\"name\":\"s-lecfilm\",\"url\":\"https:\\\/\\\/www.s-lecfilm.com\\\/de\\\/\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.s-lecfilm.com\\\/de\\\/innovation\\\/#webpage\",\"url\":\"https:\\\/\\\/www.s-lecfilm.com\\\/de\\\/innovation\\\/\",\"name\":\"PVB-Zwischenschicht Innovation | SEKISUI S-LEC\",\"description\":\"Um die neuesten Innovationen bei PVB-Zwischenschichtfolien f\\u00fcr Laminiertes Glass zu integrieren, stellen wir uns gemeinsam mit unseren Partnern weltweit der Herausforderung der offenen Innovation.\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.s-lecfilm.com\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.s-lecfilm.com\\\/de\\\/innovation\\\/#breadcrumblist\"},\"datePublished\":\"2023-01-18T10:00:00+09:00\",\"dateModified\":\"2024-06-21T16:34:14+09:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.s-lecfilm.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.s-lecfilm.com\\\/de\\\/\",\"name\":\"s-lecfilm\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.s-lecfilm.com\\\/de\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>PVB-Zwischenschicht Innovation | SEKISUI S-LEC<\/title>\n\n","aioseo_head_json":{"title":"PVB-Zwischenschicht Innovation | SEKISUI S-LEC","description":"Um die neuesten Innovationen bei PVB-Zwischenschichtfolien f\u00fcr Laminiertes Glass zu integrieren, stellen wir uns gemeinsam mit unseren Partnern weltweit der Herausforderung der offenen Innovation.","canonical_url":"https:\/\/www.s-lecfilm.com\/de\/innovation\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"LGoHK3imcI57fEDyHDnPGNxrBKyRAWvyS1_pmekTNEU","miscellaneous":""},"og:locale":"de_DE","og:site_name":"SEKISUI S-LEC","og:type":"website","og:title":"PVB-Zwischenschicht Innovation | SEKISUI S-LEC","og:description":"Um die neuesten Innovationen bei PVB-Zwischenschichtfolien f\u00fcr Laminiertes Glass zu integrieren, stellen wir uns gemeinsam mit unseren Partnern weltweit der Herausforderung der offenen Innovation.","og:url":"https:\/\/www.s-lecfilm.com\/de\/innovation\/","og:image":"https:\/\/www.s-lecfilm.com\/wp-content\/uploads\/2023\/01\/hero-innovation.jpg","og:image:secure_url":"https:\/\/www.s-lecfilm.com\/wp-content\/uploads\/2023\/01\/hero-innovation.jpg","og:image:width":1200,"og:image:height":659,"twitter:card":"summary_large_image","twitter:title":"PVB-Zwischenschicht Innovation | SEKISUI S-LEC","twitter:description":"Um die neuesten Innovationen bei PVB-Zwischenschichtfolien f\u00fcr Laminiertes Glass zu integrieren, stellen wir uns gemeinsam mit unseren Partnern weltweit der Herausforderung der offenen Innovation.","twitter:image":"https:\/\/www.s-lecfilm.com\/wp-content\/uploads\/2023\/01\/hero-innovation.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.s-lecfilm.com\/de\/innovation\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.s-lecfilm.com\/de\/#listItem","position":1,"name":"Zu Hause","item":"https:\/\/www.s-lecfilm.com\/de\/","nextItem":"https:\/\/www.s-lecfilm.com\/de\/innovation\/#listItem"},{"@type":"ListItem","@id":"https:\/\/www.s-lecfilm.com\/de\/innovation\/#listItem","position":2,"name":"\/de\/innovation\/","previousItem":"https:\/\/www.s-lecfilm.com\/de\/#listItem"}]},{"@type":"Organization","@id":"https:\/\/www.s-lecfilm.com\/de\/#organization","name":"s-lecfilm","url":"https:\/\/www.s-lecfilm.com\/de\/"},{"@type":"WebPage","@id":"https:\/\/www.s-lecfilm.com\/de\/innovation\/#webpage","url":"https:\/\/www.s-lecfilm.com\/de\/innovation\/","name":"PVB-Zwischenschicht Innovation | SEKISUI S-LEC","description":"Um die neuesten Innovationen bei PVB-Zwischenschichtfolien f\u00fcr Laminiertes Glass zu integrieren, stellen wir uns gemeinsam mit unseren Partnern weltweit der Herausforderung der offenen Innovation.","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/www.s-lecfilm.com\/de\/#website"},"breadcrumb":{"@id":"https:\/\/www.s-lecfilm.com\/de\/innovation\/#breadcrumblist"},"datePublished":"2023-01-18T10:00:00+09:00","dateModified":"2024-06-21T16:34:14+09:00"},{"@type":"WebSite","@id":"https:\/\/www.s-lecfilm.com\/de\/#website","url":"https:\/\/www.s-lecfilm.com\/de\/","name":"s-lecfilm","inLanguage":"de-DE","publisher":{"@id":"https:\/\/www.s-lecfilm.com\/de\/#organization"}}]}},"aioseo_meta_data":{"post_id":"18438","title":"PVB-Zwischenschicht Innovation | SEKISUI S-LEC","description":"Um die neuesten Innovationen bei PVB-Zwischenschichtfolien f\u00fcr Laminiertes Glass zu integrieren, stellen wir uns gemeinsam mit unseren Partnern weltweit der Herausforderung der offenen Innovation.","keywords":null,"keyphrases":"{\"focus\":{\"keyphrase\":\"\",\"score\":0,\"analysis\":{\"keyphraseInTitle\":{\"score\":0,\"maxScore\":9,\"error\":1}}},\"additional\":[]}","primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"website","og_image_type":"custom_image","og_image_url":"https:\/\/www.s-lecfilm.com\/wp-content\/uploads\/2023\/01\/hero-innovation.jpg","og_image_width":"0","og_image_height":"0","og_image_custom_url":"https:\/\/www.s-lecfilm.com\/wp-content\/uploads\/2023\/01\/hero-innovation.jpg","og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"custom_image","twitter_image_url":"https:\/\/www.s-lecfilm.com\/wp-content\/uploads\/2023\/01\/hero-innovation.jpg","twitter_image_custom_url":"https:\/\/www.s-lecfilm.com\/wp-content\/uploads\/2023\/01\/hero-innovation.jpg","twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":{"title":{"suggestions":[],"usage":0},"description":{"suggestions":[],"usage":0}},"created":"2024-03-13 06:36:07","updated":"2024-06-21 07:34:48"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.s-lecfilm.com\/de\/\" title=\"\u30db\u30fc\u30e0\">\u30db\u30fc\u30e0<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\/de\/innovation\/\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"\u30db\u30fc\u30e0","link":"https:\/\/www.s-lecfilm.com\/de\/"},{"label":"\/de\/innovation\/","link":"https:\/\/www.s-lecfilm.com\/de\/innovation\/"}],"_links":{"self":[{"href":"https:\/\/www.s-lecfilm.com\/de\/wp-json\/wp\/v2\/pages\/18438"}],"collection":[{"href":"https:\/\/www.s-lecfilm.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.s-lecfilm.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.s-lecfilm.com\/de\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.s-lecfilm.com\/de\/wp-json\/wp\/v2\/comments?post=18438"}],"version-history":[{"count":8,"href":"https:\/\/www.s-lecfilm.com\/de\/wp-json\/wp\/v2\/pages\/18438\/revisions"}],"predecessor-version":[{"id":23027,"href":"https:\/\/www.s-lecfilm.com\/de\/wp-json\/wp\/v2\/pages\/18438\/revisions\/23027"}],"wp:attachment":[{"href":"https:\/\/www.s-lecfilm.com\/de\/wp-json\/wp\/v2\/media?parent=18438"}],"wp:term":[{"taxonomy":"page_category","embeddable":true,"href":"https:\/\/www.s-lecfilm.com\/de\/wp-json\/wp\/v2\/page_category?post=18438"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}